{"id":13304,"date":"2025-04-11T01:18:20","date_gmt":"2025-04-11T05:18:20","guid":{"rendered":"http:\/\/memoriasantalucia162.cl\/wp\/?p=13304"},"modified":"2025-04-11T01:18:22","modified_gmt":"2025-04-11T05:18:22","slug":"ciclo-de-teatro-abril-dina-1974-la-clinica","status":"publish","type":"post","link":"http:\/\/memoriasantalucia162.cl\/wp\/ciclo-de-teatro-abril-dina-1974-la-clinica\/","title":{"rendered":"Ciclo de Teatro Abril: &#8220;Dina 1974 &#8211; La Cl\u00ednica&#8221;"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-576x1024.jpeg\" alt=\"\" class=\"wp-image-13305\" srcset=\"http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-169x300.jpeg 169w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-200x356.jpeg 200w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-400x711.jpeg 400w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-576x1024.jpeg 576w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-600x1067.jpeg 600w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-768x1365.jpeg 768w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-800x1422.jpeg 800w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974-864x1536.jpeg 864w, http:\/\/memoriasantalucia162.cl\/wp\/wp-content\/uploads\/2025\/04\/Dina1974.jpeg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p>Teatro en Casa junto al Sitio de Memoria Ex Cl\u00ednica Santa Luc\u00eda abren las puertas de esta casona para hacer memoria y visibilizar la historia a\u00fan desconocida para muchas personas de uno de los recintos clandestinos de la dictadura c\u00edvico militar m\u00e1s siniestros que oper\u00f3 en los primeros tiempos de reprensi\u00f3n a cargo de m\u00e9dicos, enfermeras y personal de salud que sirvieron a los prop\u00f3sitos de Pinochet y Contreras.\u00a0<\/p>\n\n\n\n<p>A trav\u00e9s de una visita guiada, una de sus principales agentes, la enfermera Eliana Bolumbur\u00fa (La Dama del Pentotal), nos har\u00e1 transitar por este espacio, hoy declarado sitio de memoria y monumento nacional en categor\u00eda hist\u00f3rico.<\/p>\n\n\n\n<p>Este es resultado de una investigaci\u00f3n de 4 a\u00f1os de trabajo para desentra\u00f1ar cu\u00e1les son los motivos por los que los m\u00e9dicos que trabajaron para la DINA decidieron romper su juramento.<\/p>\n\n\n\n<p>FUNCIONES: 10 al 26 de abril, 20.30 horas (jueves, viernes y s\u00e1bados)<\/p>\n\n\n\n<p>Entradas: Adhesi\u00f3n Sugerida, $3000, $5000, $8000<\/p>\n\n\n\n<p>Escribir a reservas.teatroencasa@gmail.com para asegurar cupo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teatro en Casa junto al Sitio de Memoria Ex Cl\u00ednica Santa Luc\u00eda abren las puertas de esta casona para hacer memoria y visibilizar la historia a\u00fan desconocida para muchas personas de uno de los recintos clandestinos de la dictadura c\u00edvico militar m\u00e1s siniestros que oper\u00f3 en los primeros tiempos de reprensi\u00f3n a cargo de m\u00e9dicos, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[56],"tags":[54,41,44,48,43,46,55,51],"_links":{"self":[{"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/posts\/13304"}],"collection":[{"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/comments?post=13304"}],"version-history":[{"count":1,"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/posts\/13304\/revisions"}],"predecessor-version":[{"id":13306,"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/posts\/13304\/revisions\/13306"}],"wp:attachment":[{"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/media?parent=13304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/categories?post=13304"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/memoriasantalucia162.cl\/wp\/wp-json\/wp\/v2\/tags?post=13304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}